{"id":709,"date":"2024-10-10T17:53:41","date_gmt":"2024-10-10T20:53:41","guid":{"rendered":"https:\/\/qladvogados.com.br\/?p=709"},"modified":"2024-12-30T16:42:34","modified_gmt":"2024-12-30T19:42:34","slug":"confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular","status":"publish","type":"post","link":"https:\/\/qladvogados.com.br\/en\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/","title":{"rendered":"(PT) CONFAZ altera regras de ICMS na transfer\u00eancia interestadual de mercadorias entre estabelecimentos do mesmo titular"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/qladvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/709\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":1,"featured_media":800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONFAZ altera regras de ICMS<\/title>\n<meta name=\"description\" content=\"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\/2024, que regulamenta a transfer\u00eancia de juros anuais de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONFAZ altera regras de ICMS\" \/>\n<meta property=\"og:description\" content=\"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\/2024, que regulamenta a transfer\u00eancia de juros anuais de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/\" \/>\n<meta property=\"og:site_name\" content=\"Queiroz e Lautenschl\u00e4ger Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T20:53:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T19:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"qla.letsite.com.br\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"qla.letsite.com.br\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/\"},\"author\":{\"name\":\"qla.letsite.com.br\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"headline\":\"(PT) CONFAZ altera regras de ICMS na transfer\u00eancia interestadual de mercadorias entre estabelecimentos do mesmo titular\",\"datePublished\":\"2024-10-10T20:53:41+00:00\",\"dateModified\":\"2024-12-30T19:42:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/\"},\"wordCount\":415,\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/\",\"name\":\"CONFAZ altera regras de ICMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png\",\"datePublished\":\"2024-10-10T20:53:41+00:00\",\"dateModified\":\"2024-12-30T19:42:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"description\":\"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\\\/2024, que regulamenta a transfer\u00eancia de juros anuais de...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png\",\"contentUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/qladvogados.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONFAZ altera regras de ICMS na transfer\u00eancia interestadual de mercadorias entre estabelecimentos do mesmo titular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/\",\"name\":\"Queiroz e Lautenschl\u00e4ger Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qladvogados.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\",\"name\":\"qla.letsite.com.br\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"qla.letsite.com.br\"},\"sameAs\":[\"https:\\\/\\\/qladvogados.com.br\"],\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/en\\\/author\\\/qla-letsite-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONFAZ altera regras de ICMS","description":"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\/2024, que regulamenta a transfer\u00eancia de juros anuais de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/","og_locale":"en_US","og_type":"article","og_title":"CONFAZ altera regras de ICMS","og_description":"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\/2024, que regulamenta a transfer\u00eancia de juros anuais de...","og_url":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/","og_site_name":"Queiroz e Lautenschl\u00e4ger Advogados","article_published_time":"2024-10-10T20:53:41+00:00","article_modified_time":"2024-12-30T19:42:34+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png","type":"image\/png"}],"author":"qla.letsite.com.br","twitter_card":"summary_large_image","twitter_misc":{"Written by":"qla.letsite.com.br","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#article","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/"},"author":{"name":"qla.letsite.com.br","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"headline":"(PT) CONFAZ altera regras de ICMS na transfer\u00eancia interestadual de mercadorias entre estabelecimentos do mesmo titular","datePublished":"2024-10-10T20:53:41+00:00","dateModified":"2024-12-30T19:42:34+00:00","mainEntityOfPage":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/"},"wordCount":415,"image":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/","url":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/","name":"CONFAZ altera regras de ICMS","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#primaryimage"},"image":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png","datePublished":"2024-10-10T20:53:41+00:00","dateModified":"2024-12-30T19:42:34+00:00","author":{"@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"description":"CONFAZ altera regras de ICMS com a publica\u00e7\u00e3o do Conv\u00eanio ICMS 109\/2024, que regulamenta a transfer\u00eancia de juros anuais de...","breadcrumb":{"@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#primaryimage","url":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png","contentUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-2024-10-10T175727.738-1024x683-1.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/qladvogados.com.br\/confaz-altera-regras-de-icms-na-transferencia-interestadual-de-mercadorias-entre-estabelecimentos-do-mesmo-titular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/qladvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"CONFAZ altera regras de ICMS na transfer\u00eancia interestadual de mercadorias entre estabelecimentos do mesmo titular"}]},{"@type":"WebSite","@id":"https:\/\/qladvogados.com.br\/#website","url":"https:\/\/qladvogados.com.br\/","name":"Queiroz e Lautenschl\u00e4ger Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qladvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f","name":"qla.letsite.com.br","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"qla.letsite.com.br"},"sameAs":["https:\/\/qladvogados.com.br"],"url":"https:\/\/qladvogados.com.br\/en\/author\/qla-letsite-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=709"}],"version-history":[{"count":0,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media\/800"}],"wp:attachment":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}