{"id":593,"date":"2024-08-16T16:12:36","date_gmt":"2024-08-16T19:12:36","guid":{"rendered":"http:\/\/qladvogados.com.br\/?p=593"},"modified":"2024-12-30T16:49:30","modified_gmt":"2024-12-30T19:49:30","slug":"julgamento-simulado-trabalhista-2","status":"publish","type":"post","link":"https:\/\/qladvogados.com.br\/en\/julgamento-simulado-trabalhista-2\/","title":{"rendered":"(PT) Estagi\u00e1rios | Julgamento Simulado Trabalhista"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/qladvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/593\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":1,"featured_media":778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Julgamento Simulado Trabalhista<\/title>\n<meta name=\"description\" content=\"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julgamento Simulado Trabalhista\" \/>\n<meta property=\"og:description\" content=\"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Queiroz e Lautenschl\u00e4ger Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-16T19:12:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T19:49:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"qla.letsite.com.br\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"qla.letsite.com.br\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/\"},\"author\":{\"name\":\"qla.letsite.com.br\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"headline\":\"(PT) Estagi\u00e1rios | Julgamento Simulado Trabalhista\",\"datePublished\":\"2024-08-16T19:12:36+00:00\",\"dateModified\":\"2024-12-30T19:49:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/\"},\"wordCount\":111,\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-82-1024x683-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/\",\"name\":\"Julgamento Simulado Trabalhista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-82-1024x683-1.png\",\"datePublished\":\"2024-08-16T19:12:36+00:00\",\"dateModified\":\"2024-12-30T19:49:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"description\":\"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-82-1024x683-1.png\",\"contentUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-82-1024x683-1.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/julgamento-simulado-trabalhista-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/qladvogados.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estagi\u00e1rios | Julgamento Simulado Trabalhista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/\",\"name\":\"Queiroz e Lautenschl\u00e4ger Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qladvogados.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\",\"name\":\"qla.letsite.com.br\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"qla.letsite.com.br\"},\"sameAs\":[\"https:\\\/\\\/qladvogados.com.br\"],\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/en\\\/author\\\/qla-letsite-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Julgamento Simulado Trabalhista","description":"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/","og_locale":"en_US","og_type":"article","og_title":"Julgamento Simulado Trabalhista","og_description":"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).","og_url":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/","og_site_name":"Queiroz e Lautenschl\u00e4ger Advogados","article_published_time":"2024-08-16T19:12:36+00:00","article_modified_time":"2024-12-30T19:49:30+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png","type":"image\/png"}],"author":"qla.letsite.com.br","twitter_card":"summary_large_image","twitter_misc":{"Written by":"qla.letsite.com.br","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#article","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/"},"author":{"name":"qla.letsite.com.br","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"headline":"(PT) Estagi\u00e1rios | Julgamento Simulado Trabalhista","datePublished":"2024-08-16T19:12:36+00:00","dateModified":"2024-12-30T19:49:30+00:00","mainEntityOfPage":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/"},"wordCount":111,"image":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/","url":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/","name":"Julgamento Simulado Trabalhista","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#primaryimage"},"image":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png","datePublished":"2024-08-16T19:12:36+00:00","dateModified":"2024-12-30T19:49:30+00:00","author":{"@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"description":"Neste segundo epis\u00f3dio da s\u00e9rie \u201cJulgamento Simulado Trabalhista\u201d, ouvimos os protagonistas desse evento que s\u00e3o os estagi\u00e1rios(as).","breadcrumb":{"@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#primaryimage","url":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png","contentUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-82-1024x683-1.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/qladvogados.com.br\/julgamento-simulado-trabalhista-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/qladvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"Estagi\u00e1rios | Julgamento Simulado Trabalhista"}]},{"@type":"WebSite","@id":"https:\/\/qladvogados.com.br\/#website","url":"https:\/\/qladvogados.com.br\/","name":"Queiroz e Lautenschl\u00e4ger Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qladvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f","name":"qla.letsite.com.br","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"qla.letsite.com.br"},"sameAs":["https:\/\/qladvogados.com.br"],"url":"https:\/\/qladvogados.com.br\/en\/author\/qla-letsite-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":0,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media\/778"}],"wp:attachment":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}