{"id":590,"date":"2024-08-15T16:00:45","date_gmt":"2024-08-15T19:00:45","guid":{"rendered":"http:\/\/qladvogados.com.br\/?p=590"},"modified":"2024-12-30T16:49:56","modified_gmt":"2024-12-30T19:49:56","slug":"analise-advocacia-diversidade-e-inclusao","status":"publish","type":"post","link":"https:\/\/qladvogados.com.br\/en\/analise-advocacia-diversidade-e-inclusao\/","title":{"rendered":"(PT) Fomos listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o 2024"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/qladvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/590\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":1,"featured_media":777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lise Advocacia Diversidade e Inclus\u00e3o<\/title>\n<meta name=\"description\" content=\"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lise Advocacia Diversidade e Inclus\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/\" \/>\n<meta property=\"og:site_name\" content=\"Queiroz e Lautenschl\u00e4ger Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-15T19:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T19:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"qla.letsite.com.br\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"qla.letsite.com.br\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/\"},\"author\":{\"name\":\"qla.letsite.com.br\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"headline\":\"(PT) Fomos listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o 2024\",\"datePublished\":\"2024-08-15T19:00:45+00:00\",\"dateModified\":\"2024-12-30T19:49:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/\"},\"wordCount\":106,\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-81-1024x683-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/\",\"name\":\"An\u00e1lise Advocacia Diversidade e Inclus\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-81-1024x683-1.png\",\"datePublished\":\"2024-08-15T19:00:45+00:00\",\"dateModified\":\"2024-12-30T19:49:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\"},\"description\":\"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-81-1024x683-1.png\",\"contentUrl\":\"https:\\\/\\\/qladvogados.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/arte-site-OC-81-1024x683-1.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/analise-advocacia-diversidade-e-inclusao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/qladvogados.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fomos listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/\",\"name\":\"Queiroz e Lautenschl\u00e4ger Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qladvogados.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#\\\/schema\\\/person\\\/ef81f10b8ca196aad1c1eb625736031f\",\"name\":\"qla.letsite.com.br\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"qla.letsite.com.br\"},\"sameAs\":[\"https:\\\/\\\/qladvogados.com.br\"],\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/en\\\/author\\\/qla-letsite-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lise Advocacia Diversidade e Inclus\u00e3o","description":"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/","og_locale":"en_US","og_type":"article","og_title":"An\u00e1lise Advocacia Diversidade e Inclus\u00e3o","og_description":"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.","og_url":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/","og_site_name":"Queiroz e Lautenschl\u00e4ger Advogados","article_published_time":"2024-08-15T19:00:45+00:00","article_modified_time":"2024-12-30T19:49:56+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png","type":"image\/png"}],"author":"qla.letsite.com.br","twitter_card":"summary_large_image","twitter_misc":{"Written by":"qla.letsite.com.br","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#article","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/"},"author":{"name":"qla.letsite.com.br","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"headline":"(PT) Fomos listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o 2024","datePublished":"2024-08-15T19:00:45+00:00","dateModified":"2024-12-30T19:49:56+00:00","mainEntityOfPage":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/"},"wordCount":106,"image":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/","url":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/","name":"An\u00e1lise Advocacia Diversidade e Inclus\u00e3o","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#primaryimage"},"image":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#primaryimage"},"thumbnailUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png","datePublished":"2024-08-15T19:00:45+00:00","dateModified":"2024-12-30T19:49:56+00:00","author":{"@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f"},"description":"Estamos orgulhosos de ser listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o por mais um ano. A diversidade n\u00e3o \u00e9 apenas um compromisso, mas parte fundamental da nossa responsabilidade social.","breadcrumb":{"@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#primaryimage","url":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png","contentUrl":"https:\/\/qladvogados.com.br\/wp-content\/uploads\/2024\/11\/arte-site-OC-81-1024x683-1.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/qladvogados.com.br\/analise-advocacia-diversidade-e-inclusao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/qladvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"Fomos listados pela An\u00e1lise Advocacia Diversidade e Inclus\u00e3o 2024"}]},{"@type":"WebSite","@id":"https:\/\/qladvogados.com.br\/#website","url":"https:\/\/qladvogados.com.br\/","name":"Queiroz e Lautenschl\u00e4ger Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qladvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/qladvogados.com.br\/#\/schema\/person\/ef81f10b8ca196aad1c1eb625736031f","name":"qla.letsite.com.br","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"qla.letsite.com.br"},"sameAs":["https:\/\/qladvogados.com.br"],"url":"https:\/\/qladvogados.com.br\/en\/author\/qla-letsite-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":0,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media\/777"}],"wp:attachment":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}