{"id":459,"date":"2024-06-12T10:14:09","date_gmt":"2024-06-12T13:14:09","guid":{"rendered":"https:\/\/qladvogados.com.br\/?post_type=area&#038;p=459"},"modified":"2024-06-14T21:53:08","modified_gmt":"2024-06-15T00:53:08","slug":"propriedade-intelectual-e-privacidade","status":"publish","type":"area","link":"https:\/\/qladvogados.com.br\/en\/area\/propriedade-intelectual-e-privacidade\/","title":{"rendered":"Intellectual Property and Privacy"},"content":{"rendered":"<p>Our work focused on the protection and defense of intellectual property and privacy includes:<\/p>\n<ul>\n<li>Drafting, reviewing, and negotiating contracts for publishing, licensing, and assignment of intellectual property rights, among others;<\/li>\n<li>Providing advice on various issues related to copyright, entertainment law, image rights, trademarks, software, internet law, privacy, and LGPD (Brazil&#8217;s General Data Protection Law), through case analysis and the preparation of legal opinions;<\/li>\n<li>Assisting in trademark registration procedures before the Brazilian National Institute of Industrial Property (INPI);<\/li>\n<li>Consulting on copyright matters: protection of literary, audiovisual, architectural, and general artistic works;<\/li>\n<li>Representing our clients in judicial disputes involving the infringement of intellectual property rights: plagiarism, unfair competition, trademark imitation, violation of personality rights, etc.<\/li>\n<\/ul>\n<p><\/p>","protected":false},"featured_media":0,"parent":0,"template":"","class_list":["post-459","area","type-area","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intellectual Property and Privacy - Queiroz e Lautenschl\u00e4ger Advogados<\/title>\n<meta name=\"description\" content=\"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Propriedade Intelectual e Privacidade[:en]Intellectual Property and Privacy[:] - Queiroz e Lautenschl\u00e4ger Advogados\" \/>\n<meta property=\"og:description\" content=\"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Queiroz e Lautenschl\u00e4ger Advogados\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-15T00:53:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/area\\\/propriedade-intelectual-e-privacidade\\\/\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/area\\\/propriedade-intelectual-e-privacidade\\\/\",\"name\":\"[:pb]Propriedade Intelectual e Privacidade[:en]Intellectual Property and Privacy[:] - Queiroz e Lautenschl\u00e4ger Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\"},\"datePublished\":\"2024-06-12T13:14:09+00:00\",\"dateModified\":\"2024-06-15T00:53:08+00:00\",\"description\":\"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/area\\\/propriedade-intelectual-e-privacidade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qladvogados.com.br\\\/area\\\/propriedade-intelectual-e-privacidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/area\\\/propriedade-intelectual-e-privacidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/qladvogados.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriedade Intelectual e Privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qladvogados.com.br\\\/#website\",\"url\":\"https:\\\/\\\/qladvogados.com.br\\\/\",\"name\":\"Queiroz e Lautenschl\u00e4ger Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qladvogados.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Propriedade Intelectual e Privacidade[:en]Intellectual Property and Privacy[:] - Queiroz e Lautenschl\u00e4ger Advogados","description":"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/","og_locale":"en_US","og_type":"article","og_title":"[:pb]Propriedade Intelectual e Privacidade[:en]Intellectual Property and Privacy[:] - Queiroz e Lautenschl\u00e4ger Advogados","og_description":"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos","og_url":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/","og_site_name":"Queiroz e Lautenschl\u00e4ger Advogados","article_modified_time":"2024-06-15T00:53:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/","url":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/","name":"[:pb]Propriedade Intelectual e Privacidade[:en]Intellectual Property and Privacy[:] - Queiroz e Lautenschl\u00e4ger Advogados","isPartOf":{"@id":"https:\/\/qladvogados.com.br\/#website"},"datePublished":"2024-06-12T13:14:09+00:00","dateModified":"2024-06-15T00:53:08+00:00","description":"Nossa atua\u00e7\u00e3o voltada \u00e0 prote\u00e7\u00e3o e defesa da propriedade intelectual e da privacidade abrange: Elabora\u00e7\u00e3o, revis\u00e3o e negocia\u00e7\u00e3o de contratos","breadcrumb":{"@id":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/qladvogados.com.br\/area\/propriedade-intelectual-e-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/qladvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"Propriedade Intelectual e Privacidade"}]},{"@type":"WebSite","@id":"https:\/\/qladvogados.com.br\/#website","url":"https:\/\/qladvogados.com.br\/","name":"Queiroz e Lautenschl\u00e4ger Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qladvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/area\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/area"}],"about":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/types\/area"}],"wp:attachment":[{"href":"https:\/\/qladvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}